{"id":8359,"date":"2026-07-09T14:09:59","date_gmt":"2026-07-09T18:09:59","guid":{"rendered":"https:\/\/www.manaus.am.gov.br\/semtepi\/sem-categoria\/sine-manaus-779-vagas-emprego-10-7\/"},"modified":"2026-07-09T14:13:26","modified_gmt":"2026-07-09T18:13:26","slug":"sine-manaus-779-vagas-emprego-10-7","status":"publish","type":"post","link":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/","title":{"rendered":"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7"},"content":{"rendered":"\n<p>A <a href=\"https:\/\/www.manaus.am.gov.br\/\">Prefeitura de Manaus<\/a>, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7,\u00a0das 8h \u00e0s 14h. O candidato pode validar a Carteira Digital e Previd\u00eancia Social (CTPS) no aplicativo \u201cCarteira de Trabalho Digital\u201d ou acessar o site\u00a0<a href=\"http:\/\/gov.br\/trabalho\">http:\/\/gov.br\/trabalho<\/a>.<\/p>\n\n\n\n<p>Para participar da pr\u00e9-sele\u00e7\u00e3o e concorrer a uma das vagas dispon\u00edveis, ou receber orienta\u00e7\u00e3o de cadastro, Carteira de Trabalho Digital e seguro-desemprego, os candidatos devem comparecer a um dos postos do Sine Manaus: na avenida Constantino Nery, n\u00ba 1.272, bairro S\u00e3o Geraldo, zona Centro-Sul; ou no shopping Phelippe Daou, na avenida Camapu\u00e3, n\u00ba 2.939, bairro Cidade de Deus, zona Norte.<\/p>\n\n\n\n<p>Os interessados devem estar munidos do comprovante de vacina\u00e7\u00e3o (Covid-19), curr\u00edculo, certificados de cursos e documentos pessoais (RG, CPF, PIS, CTPS, comprovante de escolaridade e resid\u00eancia). N\u00e3o \u00e9 necess\u00e1rio apresentar c\u00f3pias, somente os documentos originais.<\/p>\n\n\n\n<p>\u00c9 importante que os candidatos mantenham seus cadastros atualizados, especialmente ao finalizarem novas qualifica\u00e7\u00f5es. Para vagas espec\u00edficas, podem ser solicitados documentos adicionais, como cursos ou certifica\u00e7\u00f5es, por isso, \u00e9 essencial estar atento aos &#8220;Requisitos Obrigat\u00f3rios&#8221; de cada vaga.<\/p>\n\n\n\n<p>A Semtepi ressalta que, obedecendo ao disposto no artigo 5\u00ba, da Constitui\u00e7\u00e3o Federal, e ao artigo 373-A, da Consolida\u00e7\u00e3o das Leis Trabalhistas (CLT), crit\u00e9rios referentes a sexo, idade, cor ou situa\u00e7\u00e3o familiar, n\u00e3o podem ser informados na divulga\u00e7\u00e3o das vagas disponibilizadas.<\/p>\n\n\n\n<p>Os candidatos devem estar cientes das diretrizes de vestimenta estabelecidas pelo \u00f3rg\u00e3o, as quais incluem a proibi\u00e7\u00e3o de vestimentas como bermudas, shorts, minissaias, camisetas regatas e chinelos durante a entrada.<\/p>\n\n\n\n<p><strong>VAGAS NOVAS &#8211; 230<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Atendente<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>recepcionar o p\u00fablico, esclarecer d\u00favidas, registrar pedidos ou reclama\u00e7\u00f5es, processar pagamentos e organizar o ambiente ou estoque para garantir uma experi\u00eancia de compra eficiente e cordial.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Atendente &#8211; Opera\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atuar no suporte ao cliente e na manuten\u00e7\u00e3o dos processos internos da empresa.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>50 vagas &#8211; Auxiliar de Produ\u00e7\u00e3o &#8211; Eletroeletr\u00f4nico&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter curso de TBO, NR12 e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar materiais para alimenta\u00e7\u00e3o de linhas de produ\u00e7\u00e3o; organizar a \u00e1rea de servi\u00e7o; abastecer linhas de produ\u00e7\u00e3o; alimentar m\u00e1quinas e separar materiais para reaproveitamento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Operador Multifuncional I<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, n\u00e3o residir nos bairros: Parque Mau\u00e1, Centro, Ramal do Brasileirinho, Valpara\u00edso e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar materiais para alimenta\u00e7\u00e3o de linhas de produ\u00e7\u00e3o; organizar a \u00e1rea de servi\u00e7o; abastecer linhas de produ\u00e7\u00e3o; alimentar m\u00e1quinas e separar materiais para reaproveitamento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>50 vagas &#8211; Atendente de Lanchonete<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>primeiro emprego;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparo de lanches e suas finaliza\u00e7\u00f5es; manipula\u00e7\u00e3o de m\u00e1quinas de caf\u00e9; extra\u00e7\u00e3o de bebidas quentes (caf\u00e9 e ch\u00e1); pedidos: comanda, abertura e fechamento de contas e formas de pagamento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Dep\u00f3sito<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade para trabalhar na Avenida do Turismo e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>embarque e desembarque de mercadorias pesadas; etiquetagem e organiza\u00e7\u00e3o do ambiente de trabalho.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Estoquista<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>checagem f\u00edsica das mercadorias com a nota fiscal (NF), validando quantidade, avarias e prazos de validade; registro de entradas, sa\u00eddas e transfer\u00eancias de produtos, evitando falta ou excesso no estoque; organiza\u00e7\u00e3o e endere\u00e7amento adequado dos materiais para facilitar a localiza\u00e7\u00e3o r\u00e1pida.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Servi\u00e7os Gerais<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>limpeza e conserva\u00e7\u00e3o de \u00e1reas internas e externas, lavagem de vidra\u00e7as, higieniza\u00e7\u00e3o de banheiros, recolhimento de lixo, e em alguns casos, apoio no carregamento de mercadorias pesadas ou na organiza\u00e7\u00e3o de estoques.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Mec\u00e2nico de Manuten\u00e7\u00e3o de Autom\u00f3veis<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria A e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>inspecionar, reparar e conservar m\u00e1quinas, motores e equipamentos; atuar prevenindo falhas para evitar a paralisa\u00e7\u00e3o da produ\u00e7\u00e3o, ajustando pe\u00e7as, lubrificando componentes e corrigindo defeitos mec\u00e2nicos, el\u00e9tricos ou hidr\u00e1ulicos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Gar\u00e7om<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>recepcionar os clientes, apresentar o card\u00e1pio com sugest\u00f5es, anotar e comandar pedidos, servir alimentos e bebidas, organizar o sal\u00e3o, e apresentar a conta para recebimento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Ajudante de Carga e Descarga de Mercadorias<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar no transporte rodovi\u00e1rio e na log\u00edstica, atuando na prepara\u00e7\u00e3o das viagens, carregamento, descarregamento, confer\u00eancia de notas fiscais, fixa\u00e7\u00e3o de cargas e entrega de encomendas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Assistente de Recursos Humanos<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>operacionalizar as rotinas do setor de recursos humanos, servindo como o principal elo entre os colaboradores, gestores e o departamento de pessoal; dar suporte administrativo \u00e0s contrata\u00e7\u00f5es, demiss\u00f5es, controle de benef\u00edcios e atendimento di\u00e1rio aos funcion\u00e1rios.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Auxiliar de Carga e Descarga<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar atividades de carga e descarga manual de mercadorias, movimentando produtos do estoque para os caminh\u00f5es e dos caminh\u00f5es para o estoque, sempre que necess\u00e1rio, com o objetivo de garantir o correto fluxo operacional; atuar como puxador de nota, atendendo \u00e0s solicita\u00e7\u00f5es do conferente, separando, buscando e transportando os produtos no estoque; executar atividades de carga e descarga no Porto de Manaus, dirigindo-se diretamente ao local de trabalho, encontrando-se com o motorista e iniciando as atividades no hor\u00e1rio previamente determinado, conforme a programa\u00e7\u00e3o da empresa; auxiliar o motorista nas entregas realizadas na cidade de Manaus, participando das atividades de carga e descarga durante o percurso, contribuindo para a agilidade e seguran\u00e7a das entregas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Auxiliar de Estoque<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>organizar os produtos no estoque conforme categoria e m\u00e9todo de armazenamento; realizar a movimenta\u00e7\u00e3o de produtos entre os setores quando necess\u00e1rio; manter o estoque limpo, organizado e identificado; identificar e comunicar avarias, diverg\u00eancias ou produtos com validade pr\u00f3xima ao vencimento; zelar pela integridade das mercadorias durante a movimenta\u00e7\u00e3o; utilizar corretamente os equipamentos e EPIs fornecidos pela empresa; apoiar o conferente e o encarregado de estoque nas atividades operacionais.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Auxiliar de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia no segmento eletr\u00f4nico, curso de TBO ou Leitura de Componentes, n\u00e3o residir nos bairros: Tarum\u00e3, Ponto Negra, Planalto, Parque 10, Flores, Mauazinho, Dom Pedro, Col\u00f4nia Terra Nova, Col\u00f4nia Santo Ant\u00f4nio, Parque Mau\u00e1, Centro e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar montagem de produtos na linha de produ\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Operadora de Caixa<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>registrar vendas, receber pagamentos (dinheiro, cart\u00f5es, PIX) e fechar o caixa.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Motorista de Caminh\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria D, curso de Dire\u00e7\u00e3o Defensiva, MOPP, trabalhar em escala 3&#215;4 e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>transportar cargas, preparar a realiza\u00e7\u00e3o das atividades di\u00e1rias, verificando as condi\u00e7\u00f5es de funcionamento do ve\u00edculo; examinar o plano de viagem e as caracter\u00edsticas da carga; conferir informa\u00e7\u00f5es sobre o transporte e examinar a conformidade da documenta\u00e7\u00e3o; efetuar presta\u00e7\u00e3o de contas; realizar vistoria de ve\u00edculos, detectando problemas e fazendo pequenos reparos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Atendente de Padaria<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>orientar os clientes sobre os produtos dispon\u00edveis, tirar d\u00favidas sobre ingredientes e auxiliar na escolha de p\u00e3es, doces e salgados.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Lavador de Ve\u00edculos<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar lavagem e higieniza\u00e7\u00e3o em geral de ve\u00edculos; aplicar produtos de limpeza e conserva\u00e7\u00e3o automotiva; zelar pela organiza\u00e7\u00e3o e limpeza do ambiente de trabalho; seguir padr\u00f5es de qualidade e seguran\u00e7a no servi\u00e7o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Ajudante Geral<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>apoiar as opera\u00e7\u00f5es log\u00edsticas no recebimento, armazenamento, separa\u00e7\u00e3o, confer\u00eancia, embalagem e expedi\u00e7\u00e3o de produtos, contribuindo para o bom andamento dos processos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Pintor de Autom\u00f3veis<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar superf\u00edcies para pintura (lixamento, mascaramento, limpeza); aplicar fundo, tinta e verniz com pistola; realizar polimento e acabamento; garantir qualidade e padr\u00e3o no servi\u00e7o executado; zelar pelos equipamentos e materiais de pintura.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Ajudante de Porto<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar na carga e descarga de mercadorias, bags, cont\u00eaineres, paletes e materiais diversos; organizar e movimentar cargas no cais, armaz\u00e9m e embarca\u00e7\u00f5es; auxiliar na amarra\u00e7\u00e3o e desamarra\u00e7\u00e3o de embarca\u00e7\u00f5es, quando treinado e autorizado.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Manuten\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter curso de NR 12, NR 33, NR 35 e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar atividades de apoio \u00e0 manuten\u00e7\u00e3o das instala\u00e7\u00f5es, equipamentos, ferramentas e estruturas do estaleiro, contribuindo para a conserva\u00e7\u00e3o do ambiente de trabalho, seguran\u00e7a operacional e continuidade das opera\u00e7\u00f5es.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Encarregado Operacional<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>recebimento e carregamento de cargas, faz confer\u00eancia das etiquetas, encaminhamento das cargas recebidas para as pra\u00e7as de carregamento e ou pend\u00eancias, com acompanhamento de fotos dos ve\u00edculos, relat\u00f3rios di\u00e1rios de todas as ocorr\u00eancias do turno.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Auxiliar de Produ\u00e7\u00e3o &#8211; Vagas exclusivas para Pessoa com Defici\u00eancia (PCD)<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>transporte, levantamento e organiza\u00e7\u00e3o de mat\u00e9rias-primas e produtos pesados; colocar insumos, pe\u00e7as e materiais nas m\u00e1quinas ou nas esteiras da linha de produ\u00e7\u00e3o; auxiliar no corte, montagem e manuseio de pe\u00e7as utilizando ferramentas manuais b\u00e1sicas; separar, embalar e organizar os produtos finalizados para o es<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Apoio Log\u00edstico<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; residir nos bairros: Col\u00f4nia Ant\u00f4nio Aleixo, Mauazinho, Puraquequara, Distrito Industrial II, Jorge Teixeira, S\u00e3o Jos\u00e9, Coroado, Tancredo Neves, Zumbi, Novo Aleixo, Grande Vit\u00f3ria, Armando Mendes e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar no processo log\u00edstico, controlando a entrada e sa\u00edda de mercadorias do estoque; recepcionar, conferir e armazenar produtos e materiais em dep\u00f3sito; fazer os lan\u00e7amentos da movimenta\u00e7\u00e3o de entradas e sa\u00eddas de materiais e produto acabado; fazer a distribui\u00e7\u00e3o dos produtos e materiais a serem expedidos; realizar a expedi\u00e7\u00e3o de materiais e produtos; empacotar e desempacotar materiais e insumos; organizar o dep\u00f3sito para facilitar a movimenta\u00e7\u00e3o dos itens armazenados e a armazenar; participar do processo de emiss\u00e3o de nota fiscal; examina os produtos, providenciando os despachos dos mesmos e auxilia no processo de log\u00edstica; preservar o estoque limpo e organizado; atender as demandas conforme necessidade da empresa e solicita\u00e7\u00e3o do superior imediato; zelar pela ordem e conserva\u00e7\u00e3o de ferramentas, EPI\u2019s equipamentos e materiais; cuidar da organiza\u00e7\u00e3o e limpeza do seu local de trabalho em cumprimento das normas e pol\u00edticas de qualidade e seguran\u00e7a do trabalho.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Assistente T\u00e9cnico<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino t\u00e9cnico completo em Eletrot\u00e9cnica ou Mecatr\u00f4nica;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, n\u00e3o residir nos bairros: Cidade Nova, Mauazinho, Monte das Oliveiras, Tancredo Neves, Lago Azul, Jo\u00e3o Paulo, Col\u00f4nia Ant\u00f4nio Aleixo, Col\u00f4nia Santo Ant\u00f4nio, Nova Vit\u00f3ria, Gilberto Mestrinho, Novo Israel, Grande Vit\u00f3ria, Puraquequara, S\u00e3o Jorge, Nossa Senhora das Gra\u00e7as e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar suporte log\u00edstico e administrativo, elaborar relat\u00f3rios, atender clientes e manusear documentos operacionais.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Monitor de Processos L\u00edder<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, curso de Inform\u00e1tica b\u00e1sica, n\u00e3o residir nos bairros: Cidade Nova, Mauazinho, Monte das Oliveiras, Tancredo Neves, Lago Azul, Jo\u00e3o Paulo, Col\u00f4nia Ant\u00f4nio Aleixo, Col\u00f4nia Santo Ant\u00f4nio, Nova Vit\u00f3ria, Gilberto Mestrinho, Novo Israel, Grande Vit\u00f3ria, Puraquequara, S\u00e3o Jorge, Nossa Senhora das Gra\u00e7as e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>supervisionar a execu\u00e7\u00e3o de opera\u00e7\u00f5es, garantir a ader\u00eancia \u00e0s normas, e liderar a equipe para alcan\u00e7ar as metas de efici\u00eancia e qualidade; atuar como uma ponte estrat\u00e9gica entre a equipe de base e a gest\u00e3o superior.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Alimentador de Linha de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, curso de Inform\u00e1tica b\u00e1sica, TBO, n\u00e3o residir nos bairros: Cidade Nova, Mauazinho, Monte das Oliveiras, Tancredo Neves, Lago Azul, Jo\u00e3o Paulo, Col\u00f4nia Ant\u00f4nio Aleixo, Col\u00f4nia Santo Ant\u00f4nio, Nova Vit\u00f3ria, Gilberto Mestrinho, Novo Israel, Grande Vit\u00f3ria, Puraquequara, S\u00e3o Jorge, Nossa Senhora das Gra\u00e7as e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>abastecer m\u00e1quinas e esteiras com mat\u00e9rias-primas e insumos; garantir o fluxo cont\u00ednuo da fabrica\u00e7\u00e3o, inspecionar a qualidade dos produtos, embalar mercadorias e organizar o setor industrial.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Alimentador de Linha de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, curso de Inform\u00e1tica b\u00e1sica, TBO, n\u00e3o residir nos bairros: Cidade Nova, Mauazinho, Monte das Oliveiras, Tancredo Neves, Lago Azul, Jo\u00e3o Paulo, Col\u00f4nia Ant\u00f4nio Aleixo, Col\u00f4nia Santo Ant\u00f4nio, Nova Vit\u00f3ria, Gilberto Mestrinho, Novo Israel, Grande Vit\u00f3ria, Puraquequara, S\u00e3o Jorge, Nossa Senhora das Gra\u00e7as e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>abastecer m\u00e1quinas e esteiras com mat\u00e9rias-primas e insumos; garantir o fluxo cont\u00ednuo da fabrica\u00e7\u00e3o, inspecionar a qualidade dos produtos, embalar mercadorias e organizar o setor industrial.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Auxiliar da Qualidade<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, curso de Inform\u00e1tica b\u00e1sica, TBO, Leitura de Componentes, n\u00e3o residir nos bairros: Cidade Nova, Mauazinho, Monte das Oliveiras, Tancredo Neves, Lago Azul, Jo\u00e3o Paulo, Col\u00f4nia Ant\u00f4nio Aleixo, Col\u00f4nia Santo Ant\u00f4nio, Nova Vit\u00f3ria, Gilberto Mestrinho, Novo Israel, Grande Vit\u00f3ria, Puraquequara, S\u00e3o Jorge, Nossa Senhora das Gra\u00e7as e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>apoiar a fiscaliza\u00e7\u00e3o e a padroniza\u00e7\u00e3o de processos, garantindo que produtos e servi\u00e7os estejam em conformidade com as normas; atuar inspecionando materiais, preenchendo relat\u00f3rios, identificando falhas (n\u00e3o conformidades) e acompanhando a\u00e7\u00f5es corretivas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Auxiliar de Reparo<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio, curso de Inform\u00e1tica b\u00e1sica, TBO, Leitura de Componentes, n\u00e3o residir nos bairros: Cidade Nova, Mauazinho, Monte das Oliveiras, Tancredo Neves, Lago Azul, Jo\u00e3o Paulo, Col\u00f4nia Ant\u00f4nio Aleixo, Col\u00f4nia Santo Ant\u00f4nio, Nova Vit\u00f3ria, Gilberto Mestrinho, Novo Israel, Grande Vit\u00f3ria, Puraquequara, S\u00e3o Jorge, Nossa Senhora das Gra\u00e7as e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>apoiar a equipe t\u00e9cnica ou de manuten\u00e7\u00e3o na identifica\u00e7\u00e3o de falhas, conserto de equipamentos ou estruturas e testes de funcionamento; diagnosticar defeitos, testar aparelhos reparados, organizar pe\u00e7as e documentar processos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>VAGAS NO COM\u00c9RCIO &#8211; 125<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Lavador de Ve\u00edculos<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho ou avulsa;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria B e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar a lavagem e higieniza\u00e7\u00e3o interna e externa de ve\u00edculos, efetuando a limpeza de vidros, pain\u00e9is, bancos, tapetes e demais componentes, utilizando produtos adequados para conserva\u00e7\u00e3o automotiva; secagem e acabamento dos ve\u00edculos, organiza\u00e7\u00e3o e limpeza do ambiente de trabalho, al\u00e9m de auxiliar na movimenta\u00e7\u00e3o dos ve\u00edculos quando necess\u00e1rio.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Montador de Pneus<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>desmontar e montar rodas de pneus de caminh\u00e3o; fazer balanceamento e troca de \u00f3leo e filtro.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar na produ\u00e7\u00e3o de bobinas, embalagem, carregamento e descarregamento de bobinas.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Auxiliar de Carga e Descarga&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho ou avulsa;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar separa\u00e7\u00e3o de produto de acordo com a nota fiscal e realizar carga e descarga dos produtos nos caminh\u00f5es.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Consultor de Venda Direta<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria B, conhecimento em Inform\u00e1tica b\u00e1sica e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atuar na prospec\u00e7\u00e3o e na venda direta de f\u00e1brica de ve\u00edculos para MEIs e CNPJs, locadoras, autoescolas, taxistas, PCDs, frotistas e profissionais liberais, realizando negocia\u00e7\u00f5es, elabora\u00e7\u00e3o de propostas, apresenta\u00e7\u00f5es comerciais, visitas externas e acompanhamento de todo o processo desde a prospec\u00e7\u00e3o e vendas at\u00e9 o p\u00f3s-venda.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Operador (a) de Seguros<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter conhecimento em Seguros, Matem\u00e1tica Financeira e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atuar na comercializa\u00e7\u00e3o de seguros, orientando clientes, acompanhando propostas, ap\u00f3lices e renova\u00e7\u00f5es, prestando suporte no p\u00f3s-venda e apoiando a equipe de vendas com treinamentos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>4 vagas &#8211; Lavador de Ve\u00edculos<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria B e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar a limpeza e conserva\u00e7\u00e3o interna e externa de ve\u00edculos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Atendente<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia em perfumaria e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>registrar vendas e processar pagamentos; calcular e cobrar os valores a serem pagos, emitir comprovantes fiscais, atender clientes e prestar contas ao final de cada turno.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Motorista<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria AB e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>dirigir e manobrar motocicletas e transportar cargas; efetuar pagamentos e recebimentos no desempenho das atividades, utilizar-se de capacidades comunicativas, trabalhar seguindo normas de seguran\u00e7a, higiene, qualidade e prote\u00e7\u00e3o ao meio ambiente.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Conferente<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>recebimento e confer\u00eancia das mercadorias que s\u00e3o entregues pelos fornecedores, garantido a qualidade e bom estado dos produtos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Balconista de A\u00e7ougue<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atendimento no a\u00e7ougue e controle de mercadoria das ilhas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Assistente de Vendas<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar atendimento ao cliente, gerenciamento de pedidos, elabora\u00e7\u00e3o de propostas comerciais, suporte \u00e0 equipe de vendas e organiza\u00e7\u00e3o e controle de documentos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Preparador de Ve\u00edculos<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria B, no\u00e7\u00f5es b\u00e1sicas de mec\u00e2nica e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar e movimentar ve\u00edculos, controlando p\u00e1tio, chaves, abastecimento e documenta\u00e7\u00e3o, acompanhando servi\u00e7os e garantindo organiza\u00e7\u00e3o, conserva\u00e7\u00e3o e disponibilidade para venda.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Assistente de Financiamentos e Seguros<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter conhecimento em Inform\u00e1tica b\u00e1sica, Matem\u00e1tica Financeira (hP12c) e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>respons\u00e1vel pelos processos de financiamentos, seguros e documenta\u00e7\u00e3o, garantido organiza\u00e7\u00e3o, agilidade e suporte ao time comercial.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Instalador de Acess\u00f3rios de Ve\u00edculos<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>apoiar na instala\u00e7\u00e3o de acess\u00f3rios automotivos, auxiliando nas atividades da oficina e no controle b\u00e1sico do estoque de pe\u00e7as, contribuindo para a organiza\u00e7\u00e3o e qualidade dos servi\u00e7os.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; L\u00edder de A\u00e7ougue<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter conhecimento t\u00e9cnico sobre tipos de corte e manuseio de carnes, disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>liderar a\u00e7ougueiros e balconistas, elaborando escalas de folgas, hor\u00e1rios e aplicando treinamentos; monitorar o recebimento, armazenamento e reposi\u00e7\u00e3o de mercadorias, al\u00e9m de controlar o estoque; garantir a limpeza das c\u00e2maras frias, balc\u00f5es e ferramentas, seguindo normas da Vigil\u00e2ncia Sanit\u00e1ria; supervisionar os cortes de carne, pesagem e exposi\u00e7\u00e3o nos balc\u00f5es, visando o cumprimento de metas e redu\u00e7\u00e3o de perdas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; A\u00e7ougueiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho ou avulsa;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atendimento ao cliente; desossa e prepara\u00e7\u00e3o de carnes; cortes t\u00e9cnicos e padroniza\u00e7\u00e3o; prepara\u00e7\u00e3o e abastecimento para exposi\u00e7\u00e3o; apoio ao estoque, armazenamento e controle de validade.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Auxiliar de A\u00e7ougue<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho ou avulsa;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>fazer atendimento ao cliente e fornecer orienta\u00e7\u00e3o sobre carnes, adquirindo habilidade no preparo; ajudar o a\u00e7ougueiro no corte de carne, separa\u00e7\u00e3o e desossa; reportar-se ao l\u00edder de a\u00e7ougue.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Ajudante de A\u00e7ougue<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>fazer atendimento ao cliente e fornecer orienta\u00e7\u00e3o sobre carnes, adquirindo habilidade no preparo; ajudar o a\u00e7ougueiro no corte de carne, separa\u00e7\u00e3o e desossa; reportar-se ao l\u00edder de a\u00e7ougue.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Peixeiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho ou avulsa;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter conhecimento em limpeza, corte de pescados; disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar limpeza, corte e preparo de peixes em geral; organizar e abastecer a banca de pescados; verificar qualidade, conserva\u00e7\u00e3o e validade dos produtos; garantir higiene, limpeza e organiza\u00e7\u00e3o do setor; atender clientes e realizar cortes conforme solicita\u00e7\u00e3o; apoiar no controle de perdas e armazenamento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Ajudante de Peixaria<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar na limpeza, corte e preparo de peixes em geral; organizar e abastecer a banca de pescados.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Conferente<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>receber, conferir e armazenar mercadorias; verificar validade dos produtos; registrar movimenta\u00e7\u00f5es no sistema; elaborar relat\u00f3rios; controle e acuracidade de estoque.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Repositor de FLV<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>repor as mercadorias nas bancadas, ilhas e geladeiras conforme o layout da loja; retirar frutas, legumes e verduras que estejam amassados, passados ou impr\u00f3prios para consumo; higienizar constantemente os expositores, bancas e c\u00e2maras frias.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Repositor de Loja<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>repor as mercadorias nas bancadas, ilhas e geladeiras conforme o layout da loja; retirar frutas, legumes e verduras que estejam amassados, passados ou impr\u00f3prios para consumo; higienizar constantemente os expositores, bancas e c\u00e2maras frias.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Fiscal de Caixa<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atuar como um supervisor, sendo respons\u00e1vel por providenciar troco, autorizar cancelamentos, controlar os operadores e lidar com o fechamento do movimento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Operador de Loja<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar os clientes a localizar produtos, esclarecer d\u00favidas e lidar com trocas; abastecer g\u00f4ndolas e manter o espa\u00e7o limpo e atrativo; verificar datas de validade, evitar perdas e fazer o rod\u00edzio de produtos; registrar itens, processar pagamentos e fechar o caixa.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Operador de Padaria<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter conhecimento em limpeza, corte de pescados; disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atendimento ao cliente, prepara\u00e7\u00e3o r\u00e1pida de itens (como caf\u00e9s e lanches) e organiza\u00e7\u00e3o do setor; atua como a ponte entre a produ\u00e7\u00e3o e os consumidores, garantindo um servi\u00e7o \u00e1gil e de qualidade.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Montador de Pneus<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar troca de pneus e v\u00e1lvulas, montagem e desmontagem de pneus e balanceamento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Vendedor (a) Interno<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria B e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>demonstrar os produtos\/servi\u00e7os, elaborar propostas comerciais e negociar pre\u00e7os, descontos e prazos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Barcelos\/AM e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atendimento ao cliente e aux\u00edlio na escolha de produtos; demonstra\u00e7\u00e3o de funcionamento, qualidades e vantagens dos produtos; registro de entrada e sa\u00edda de mercadorias no sistema; exposi\u00e7\u00e3o e organiza\u00e7\u00e3o de mercadorias no ponto de venda.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Cozinheiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Barcelos\/AM e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>organizar e supervisionar servi\u00e7os de cozinha em hot\u00e9is, restaurantes, hospitais, resid\u00eancias e outros locais de refei\u00e7\u00f5es, planejando card\u00e1pios e elaborando o pr\u00e9-preparo, o preparo e a finaliza\u00e7\u00e3o de alimentos, observando m\u00e9todos de coc\u00e7\u00e3o e padr\u00f5es de qualidade dos alimentos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Vendedor Interno<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia em venda de artigos esportivos, residir no Bairro Parque 10 ou proximidades e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>vender mercadorias em estabelecimentos do com\u00e9rcio varejista ou atacadista, auxiliando os clientes na escolha; registrar entrada e sa\u00edda de mercadorias; promover a venda de mercadorias, demonstrando seu funcionamento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Ajudante de Dep\u00f3sito<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; residir no bairro Novo Aleixo ou proximidades e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>carregar\/descarregar caminh\u00f5es, conferir e armazenar mercadorias, separar e embalar pedidos para envio, al\u00e9m de manter o estoque organizado e auxiliar no controle de invent\u00e1rio.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Analista Fiscal<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia na \u00e1rea fiscal com apura\u00e7\u00e3o de impostos, obriga\u00e7\u00f5es acess\u00f3rias e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>apura\u00e7\u00e3o de impostos mensais (ICMS, ISS, PIS, COFINS, IRPJ e CSLL), a escritura\u00e7\u00e3o de notas fiscais, o envio de obriga\u00e7\u00f5es acess\u00f3rias (como SPED Fiscal e DCTF) e o cumprimento rigoroso da legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>dar suporte direto ao cozinheiro ou chef; pr\u00e9-preparo de alimentos, higieniza\u00e7\u00e3o do ambiente e utens\u00edlios, al\u00e9m do controle b\u00e1sico de estoque, atuando sob rigorosas normas de seguran\u00e7a e higiene.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>VAGAS NA IND\u00daSTRIA &#8211; 121<\/strong><\/p>\n\n\n\n<p><strong>50 vagas &#8211; Alimentador de Linha de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211;<\/strong> n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Promiss\u00e3o-SP e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar atividades operacionais em setores de apoio ou produ\u00e7\u00e3o, visando garantir a manuten\u00e7\u00e3o, organiza\u00e7\u00e3o e opera\u00e7\u00e3o de atividades na unidade; seguir rigorosamente as instru\u00e7\u00f5es referente aos padr\u00f5es de qualidade da empresa e seguran\u00e7a.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Desossador<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211;<\/strong> seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Promiss\u00e3o-SP e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar atividades operacionais em setores de apoio ou produ\u00e7\u00e3o, visando garantir a manuten\u00e7\u00e3o, organiza\u00e7\u00e3o e opera\u00e7\u00e3o de atividades na unidade; seguir rigorosamente as instru\u00e7\u00f5es referente aos padr\u00f5es de qualidade da empresa e seguran\u00e7a.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Abatedor<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211;<\/strong> seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Promiss\u00e3o-SP e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>padroniza\u00e7\u00e3o das pe\u00e7as de origem bovina e modelagem de cortes nobres, visando garantir o atendimento a ficha t\u00e9cnica; propiciar o aumento de rendimento do setor de abate, por meio da realiza\u00e7\u00e3o de cortes com exatid\u00e3o de hematomas, gorduras na carca\u00e7a abatida; garantir o toalete das pe\u00e7as, por meio do acompanhamento da ficha t\u00e9cnica e orienta\u00e7\u00f5es dos superiores; garantir a correta limpeza das pe\u00e7as de bucho, por meio da retirada do excesso de gordura e separando o buchinho e o abomaso; auxiliar a etapa de serragem de meia carca\u00e7a e ponta de agulha, por meio da modelagem das pe\u00e7as nobres utilizando faca.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Magarefe<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211;<\/strong> seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Promiss\u00e3o-SP e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>abate e processamento de animais (bovinos, su\u00ednos, caprinos e aves); atuar principalmente em matadouros, frigor\u00edficos e ind\u00fastrias de carne.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Auxiliar de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>identificar mat\u00e9rias-primas, embalagens ou materiais com defeitos, separando-os e os repondo, para continuidade da produ\u00e7\u00e3o; introduzir, em sistemas computacionais de gest\u00e3o de linhas de produ\u00e7\u00e3o, informa\u00e7\u00f5es sobre a quantidade de itens no posto de trabalho; encaminhar os itens n\u00e3o-conformes, mas que podem ser reciclados, para o setor respons\u00e1vel pelo reaproveitamento; solicitar, em sistema informatizado, baixa e reposi\u00e7\u00e3o dos demais itens; organizar e mant\u00e9m limpa a \u00e1rea de trabalho, acondicionando materiais; recolher e fazer descarte de res\u00edduos, seguindo procedimentos da empresa.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>4 vagas &#8211; Auxiliar de Expedi\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar a carga e descarga dos ve\u00edculos; realizar separa\u00e7\u00e3o dos pedidos conforme nota fiscal; realizar a movimenta\u00e7\u00e3o de produtos no armaz\u00e9m; executar o 5S na organiza\u00e7\u00e3o dos produtos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Motorista de Caminh\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria D e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar a carga e descarga dos ve\u00edculos; realizar separa\u00e7\u00e3o dos pedidos conforme nota fiscal; realizar a movimenta\u00e7\u00e3o de produtos no armaz\u00e9m; executar o 5S na organiza\u00e7\u00e3o dos produtos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Diretor de Opera\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino superior completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia em gest\u00e3o de unidade, planta industrial ou opera\u00e7\u00e3o de grande porte e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>dar suporte operacional \u00e0s diversas \u00e1reas de uma empresa; atuar na organiza\u00e7\u00e3o de documentos, atendimento ao cliente, controle de agendas, elabora\u00e7\u00e3o de planilhas e no aux\u00edlio a setores como financeiro, recursos humanos e log\u00edstica.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>VAGAS EM SERVI\u00c7O &#8211; 290<\/strong><\/p>\n\n\n\n<p><strong>50 vagas &#8211; Auxiliar de Linha de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211;<\/strong> n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: V\u00e1rzea Grande &#8211; MT e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar atividades operacionais em setores de apoio ou produ\u00e7\u00e3o de frios, visando garantir a manuten\u00e7\u00e3o, organiza\u00e7\u00e3o, limpeza ou opera\u00e7\u00e3o de atividades na unidade.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>25 vagas &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211;<\/strong> n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>a vaga \u00e9 destinada para candidatos que est\u00e3o em busca de novos desafios; o candidato vai precisar morar em: Minas Gerais ou Belo Horizonte, Nordeste e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>prepara\u00e7\u00e3o e organiza\u00e7\u00e3o de alimentos, a higieniza\u00e7\u00e3o do ambiente e dos utens\u00edlios, e o apoio direto aos cozinheiros.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; T\u00e9cnico de Telefonia<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211; <\/strong>ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios &#8211; <\/strong>ter Carteira Nacional de Habilita\u00e7\u00e3o categoria B e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>verificar equipamentos de telecomunica\u00e7\u00f5es; fazer teste de rotina; identificar e corrigir falhas no sistema de telecomunica\u00e7\u00f5es; instala\u00e7\u00e3o de internet fibra \u00f3ptica; configura\u00e7\u00e3o de roteadores e antenas da empresa de telefonia.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>pr\u00e9-preparo (cortar, lavar, descascar), montagem de pratos, higieniza\u00e7\u00e3o do local e equipamentos; controle de estoque de insumos e descarte de res\u00edduos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade para dormir no trabalho e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>higieniza\u00e7\u00e3o de legumes, cortes e desossa de prote\u00ednas, lavagem de utens\u00edlios, organiza\u00e7\u00e3o da \u00e1rea de trabalho.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Chefe de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade para dormir no trabalho, experi\u00eancia em preparar alimentos em grandes quantidades e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>gest\u00e3o de custos, planejamento de card\u00e1pio e seguran\u00e7a alimentar.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>15 vagas &#8211; Montador de M\u00f3veis<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar locais, montar m\u00f3veis padr\u00e3o e planejado, instalar e reparar m\u00f3veis de madeira ou materiais derivados (mdf\/mdp) em s\u00e9rie ou sob encomenda, seguindo projetos, normas de seguran\u00e7a e qualidade.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>15 vagas &#8211; Auxiliar de Montagem<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>dar apoio t\u00e9cnico direto ao montador de m\u00f3veis, o ajudante geral atua de forma mais ampla na log\u00edstica e manuten\u00e7\u00e3o do local de trabalho.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Oficial de Manuten\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar manuten\u00e7\u00e3o predial em telhado; hidr\u00e1ulica; alvenaria; assentamento de cer\u00e2micas; pintura.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; T\u00e9cnico e Instalador de Purificador de \u00c1gua<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria A ou B, no\u00e7\u00f5es de hidr\u00e1ulica, afinidade com ferramentas e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atendimento por rota; locomo\u00e7\u00e3o de purificadores; instala\u00e7\u00e3o de purificadores; troca de refil de purificadores.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>25 vagas &#8211; Auxiliar de Produ\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar materiais, abastecer linhas de montagem, operar m\u00e1quinas simples, inspecionar a qualidade dos produtos e organizar o ambiente de trabalho, sempre seguindo as normas de seguran\u00e7a e orienta\u00e7\u00f5es dos supervisores.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Mec\u00e2nico de Motor<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>diagnosticar, reparar e realizar a manuten\u00e7\u00e3o preventiva e corretiva de motores e sistemas de ve\u00edculos pesados e m\u00e1quinas movidas a diesel.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Auxiliar de Dep\u00f3sito<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental incompleto;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>separa\u00e7\u00e3o dos produtos para montagem das cargas de entrega, utilizando o coletor de dados conforme a ordem de separa\u00e7\u00e3o; recolher os paletes da \u00e1rea externa da empresa, objetivando a organiza\u00e7\u00e3o do estoque a ser executada pelo operador de empilhadeira a coloca\u00e7\u00e3o nos devidos lugares, 5S; organizar os produtos no dep\u00f3sito para facilitar a movimenta\u00e7\u00e3o dos itens armazenados, bem como manter o n\u00edvel das caixas nos padr\u00f5es estabelecidos pela empresa; separar os produtos no dep\u00f3sito utilizando o coletor de dados para compara\u00e7\u00e3o com as informa\u00e7\u00f5es em documento.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Promotor de Vendas<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria A e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>promover a exposi\u00e7\u00e3o dos produtos, bem como aplicar as t\u00e9cnicas de merchandising nos pontos de exposi\u00e7\u00e3o, visando ocupar o local de melhor acesso ao consumidor, de acordo com a fotografia repassada pela ind\u00fastria, mantendo o padr\u00e3o, conserva\u00e7\u00e3o e imagem dos produtos da empresa.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Armador<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar a arma\u00e7\u00e3o de acordo com o projeto, conferindo todo material a ser utilizado, fazendo a distribui\u00e7\u00e3o de pessoal e material, de acordo com a disposi\u00e7\u00e3o definida no projeto; executar desde a arma\u00e7\u00e3o de sapatas, caixas, pilares, vigas e lajes, assim como outras ferragens utilizadas no projeto.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Servente de Obras<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>prepara\u00e7\u00e3o do canteiro, transporte, carga e descarga de materiais, e auxilia profissionais como pedreiros e carpinteiros.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>8 vagas &#8211; Pintor de Obras<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>aplica\u00e7\u00e3o de massa corrida, o lixamento, a uniformiza\u00e7\u00e3o de paredes e a aplica\u00e7\u00e3o de tintas, texturas e vernizes para acabamento est\u00e9tico e prote\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>6 vagas &#8211; Pedreiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>leitura de projetos, preparo de argamassa e concreto, levantamento de paredes e alvenarias, al\u00e9m da aplica\u00e7\u00e3o de revestimentos e pisos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>4 vagas &#8211; Soldador<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>unir ou cortar pe\u00e7as de metal, ligas met\u00e1licas e termopl\u00e1sticos usando processos de aquecimento; atuar na fabrica\u00e7\u00e3o, montagem e manuten\u00e7\u00e3o de estruturas met\u00e1licas, m\u00e1quinas, equipamentos e tubula\u00e7\u00f5es, sendo pe\u00e7a-chave em setores como constru\u00e7\u00e3o civil.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>4 vagas &#8211; Encarregado de Obras<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>liderar as equipes de constru\u00e7\u00e3o, distribuir tarefas, realizar a leitura de projetos, fiscalizar a qualidade e o prazo dos servi\u00e7os e garantir o cumprimento das normas de seguran\u00e7a do trabalho.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Carpinteiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>construir, montar e reparar estruturas, pe\u00e7as e objetos de madeira.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Eletricista<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>apoiar profissionais na instala\u00e7\u00e3o, manuten\u00e7\u00e3o e reparo de sistemas el\u00e9tricos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Bombeiro Hidr\u00e1ulico<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>operacionalizar projetos, instalar e reparar redes de \u00e1gua, esgoto e g\u00e1s, al\u00e9m de realizar testes de estanqueidade e press\u00e3o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Almoxarife<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria D e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>recepcionar, conferir e armazenar produtos e materiais em almoxarifados, armaz\u00e9ns, silos e dep\u00f3sitos; fazer os lan\u00e7amentos da movimenta\u00e7\u00e3o de entradas e sa\u00eddas e controlar os estoques; distribuir produtos e materiais a serem expedidos; organizar o almoxarifado para facilitar a movimenta\u00e7\u00e3o dos itens armazenados e a armazenar.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Vendedor (a)<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>vender mercadorias em estabelecimentos do com\u00e9rcio varejista ou atacadista, auxiliar os clientes na escolha; registrar entrada e sa\u00edda de mercadorias; promover a venda de mercadorias, demonstrar seu funcionamento; informar sobre suas qualidades e vantagens de aquisi\u00e7\u00e3o; expor mercadorias de forma atrativa, em pontos estrat\u00e9gicos de vendas, com etiquetas de pre\u00e7o; prestar servi\u00e7os aos clientes, tais como: troca de mercadorias; abastecimento de ve\u00edculos; e outros servi\u00e7os correlatos; fazer invent\u00e1rio de mercadorias para reposi\u00e7\u00e3o; elaborar relat\u00f3rios de vendas, de promo\u00e7\u00f5es, de demonstra\u00e7\u00f5es e de pesquisa de pre\u00e7os.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Auxiliar de Refrigera\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar o mec\u00e2nico na instala\u00e7\u00e3o, manuten\u00e7\u00e3o preventiva e corretiva, al\u00e9m de ser respons\u00e1vel por preparar materiais e ferramentas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Meio Oficial de Refrigera\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar na instala\u00e7\u00e3o, limpeza e manuten\u00e7\u00e3o preventiva ou corretiva de sistemas de ar-condicionado e refrigera\u00e7\u00e3o, transportar equipamentos e preparar o ambiente de trabalho para o especialista.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Servi\u00e7os Gerais<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>varrer ch\u00e3o, lavar vidros, limpar banheiros, retirar lixo, repor materiais (papel, sabonete e outros), lustrar m\u00f3veis e organizar espa\u00e7os em geral.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Ajudante de Carga e Descarga<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar, movimentar, carregar e descarregar mercadorias de ve\u00edculos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Conferente de Carga e Descarga<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>preparar, movimentar, carregar e descarregar mercadorias de ve\u00edculos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>8 vagas &#8211; Ajudante de Carga e Descarga<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>movimentar mercadorias, carregando e descarregando ve\u00edculos (caminh\u00f5es, vans), garantindo a seguran\u00e7a e integridade dos produtos e auxiliando na organiza\u00e7\u00e3o do estoque, separa\u00e7\u00e3o, confer\u00eancia (notas fiscais) e expedi\u00e7\u00e3o de itens.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>fazer a lavagem, descascar e cortar alimentos; auxiliar na manipula\u00e7\u00e3o de alimentos, montagem de pratos; realizar a limpeza e organiza\u00e7\u00e3o do local de trabalho, lavar e guardar utens\u00edlios.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Chapeiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>auxiliar no preparo dos pratos; auxiliar no servi\u00e7o de montagem das bancadas; fazer a lavagem, descascar e cortar alimentos; auxiliar na manipula\u00e7\u00e3o de alimentos, montagem de pratos; realizar a limpeza e organiza\u00e7\u00e3o do local de trabalho, lavar e guardar utens\u00edlios.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar o pr\u00e9-preparo, preparo e processamento de alimentos, incluindo guarni\u00e7\u00f5es, sopas, caf\u00e9 e mingau; auxiliar no preparo de dietas e prote\u00ednas, quando solicitado; auxiliar na prepara\u00e7\u00e3o e organiza\u00e7\u00e3o do grill, incluindo reposi\u00e7\u00e3o de pratos e atendimento; organizar pratos, talheres, cubas e utens\u00edlios para distribui\u00e7\u00e3o das refei\u00e7\u00f5es.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>3 vagas &#8211; Auxiliar de Cozinha<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar o pr\u00e9-preparo, preparo e processamento de alimentos, incluindo guarni\u00e7\u00f5es, sopas, caf\u00e9 e mingau; auxiliar no preparo de dietas e prote\u00ednas, quando solicitado; auxiliar na prepara\u00e7\u00e3o e organiza\u00e7\u00e3o do grill, incluindo reposi\u00e7\u00e3o de pratos e atendimento; organizar pratos, talheres, cubas e utens\u00edlios para distribui\u00e7\u00e3o das refei\u00e7\u00f5es.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Motorista de Caminh\u00e3o Ba\u00fa<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Carteira Nacional de Habilita\u00e7\u00e3o categoria D, disponibilidade de hor\u00e1rio, disponibilidade para viagens interestaduais e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>conduzir os ve\u00edculos automotivos da institui\u00e7\u00e3o, seguindo as solicita\u00e7\u00f5es, mantendo-se informado sobre a agenda de entregas, respeitando as leis nacionais de tr\u00e2nsito e promovendo dire\u00e7\u00e3o defensiva, transporte da equipe de eventos, transporte de equipamentos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Cozinheira<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>criar e elaborar pratos e card\u00e1pios, atuar direta e indiretamente na prepara\u00e7\u00e3o dos alimentos; gerenciar brigada de cozinha e planejar as rotinas de trabalho.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar Administrativo<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter curso de Inform\u00e1tica avan\u00e7ada, disponibilidade de hor\u00e1rio, experi\u00eancia em Recursos Humanos e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>executar servi\u00e7os de apoio nas \u00e1reas de recursos humanos, administra\u00e7\u00e3o, finan\u00e7as e log\u00edstica; atender fornecedores e clientes, fornecer e receber informa\u00e7\u00f5es sobre produtos e servi\u00e7os; tratar de documentos variados, cumprir todo o procedimento necess\u00e1rio.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Estoquista<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>registrada na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211;<\/strong> recepcionar, conferir e armazenar produtos e materiais em almoxarifados, armaz\u00e9ns e dep\u00f3sitos; fazer os lan\u00e7amentos da movimenta\u00e7\u00e3o de entradas e sa\u00eddas e controlar os estoques; distribuir produtos e materiais a serem expedidos; organizar o almoxarifado para facilitar a movimenta\u00e7\u00e3o dos itens armazenados.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Mec\u00e2nico de Refrigera\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter curso de Refrigera\u00e7\u00e3o e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar limpeza em ar-condicionado, lavador de g\u00e1s, coifas, exaustores, caixas de ar, bombas d&#8217;\u00e1gua, motores el\u00e9tricos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar de Manuten\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia em higieniza\u00e7\u00e3o de dutos, equipamentos de exaust\u00e3o em cozinhas profissionais e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar pequenos reparos (el\u00e9tricos, hidr\u00e1ulicos e civis), lubrificar m\u00e1quinas, trocar l\u00e2mpadas, verificar checklists, organizar ferramentas e zelar pela seguran\u00e7a e limpeza do local ap\u00f3s o t\u00e9rmino do servi\u00e7o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>20 vagas &#8211; Ajudante de Carga e Descarga<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>movimentar mercadorias, carregando e descarregando ve\u00edculos, organizar o estoque, conferir produtos, preparar embalagens e mant\u00e9m o local de trabalho limpo e seguro, operando equipamentos como paleteiras e carrinhos para garantir que os produtos cheguem intactos ao destino, auxiliando em toda a log\u00edstica de recebimento e expedi\u00e7\u00e3o de materiais.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>1 vaga &#8211; Auxiliar Administrativo<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter Pacote Office e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>dar suporte operacional \u00e0s diversas \u00e1reas de uma empresa; atuar na organiza\u00e7\u00e3o de documentos, atendimento ao cliente, controle de agendas, elabora\u00e7\u00e3o de planilhas e no aux\u00edlio a setores como financeiro, recursos humanos e log\u00edstica.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Servente de Obras<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino fundamental completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>construir e repara funda\u00e7\u00f5es, utilizando tijolos, argamassa de reboco e chapisco; assentar tijolos de v\u00e1rios tipos utilizando argamassa, cimento e areia, fixa marcos e contramarcos nos batentes das aberturas e verifica o enquadramento das pe\u00e7as, auxiliar no trabalho de pedreiros e pintores.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Porteiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; trabalhar em escala 12&#215;36 e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>recepcionar, controlar o acesso ao condom\u00ednio de prestadores de servi\u00e7os e realizar contato via telefone com moradores, supervisionado pela administra\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Copeiro<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>manter a copa, utens\u00edlios (lou\u00e7as, copos, talheres) e equipamentos limpos e organizados.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Atendente<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>prestar atendimento ao cliente, entregar card\u00e1pios, anotar pedidos e organizar sal\u00e3o.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>10 vagas &#8211; Auxiliar de Log\u00edstica<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>tr\u00eas meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter disponibilidade de hor\u00e1rio e possuir documenta\u00e7\u00e3o completa (com dispensa militar);<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>conferir e armazenar produtos e materiais em almoxarifados, armaz\u00e9ns e dep\u00f3sitos; fazem os lan\u00e7amentos da movimenta\u00e7\u00e3o de entradas e sa\u00eddas e controlam os estoques; distribuir produtos e materiais a serem expedidos; organizar o almoxarifado para facilitar a movimenta\u00e7\u00e3o dos itens armazenados e a armazenar, preservando o estoque limpo e organizado; empacotar ou desempacotar os produtos, realizar expedi\u00e7\u00e3o de materiais e produtos, examinando-os, providenciando os despachos dos mesmos e auxiliam no processo de log\u00edstica.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>VAGAS DESTINADAS PARA PESSOAS COM DEFICI\u00caNCIA (PcDs) &#8211; 13<\/strong><\/p>\n\n\n\n<p><strong>6 vagas &#8211; Atendente de Lanchonete &#8211; Vagas exclusivas para Pessoa com Defici\u00eancia (PcD)<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo ou cursando;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar atendimento ao cliente de forma cordial, clara e eficiente; prestar informa\u00e7\u00f5es sobre produtos, servi\u00e7os e procedimentos; esclarecer d\u00favidas e orientar os clientes conforme suas necessidades.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>5 vagas &#8211; Assistente Administrativo &#8211; Vagas exclusivas para Pessoa com Defici\u00eancia (PcD)<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>n\u00e3o \u00e9 necess\u00e1rio;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>realizar tarefas administrativas e de apoio, garantindo a efici\u00eancia e efic\u00e1cia dos processos da empresa; gerenciar e organizar documentos e arquivos; atendimento telef\u00f4nico e presencial; preencher planilhas e formul\u00e1rios; atuar como intermedi\u00e1rio entre departamentos; prestar assist\u00eancia a diferentes departamentos; aux\u00edlio aos assistentes, analistas e supervisores nas atividades propostas.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p><strong>2 vagas &#8211; Auxiliar Administrativo &#8211; Vagas exclusivas para Pessoa com Defici\u00eancia (PcD)<\/strong><\/p>\n\n\n\n<p><strong>Escolaridade &#8211;<\/strong> ensino m\u00e9dio completo;<\/p>\n\n\n\n<p><strong>Experi\u00eancia &#8211; <\/strong>seis meses na Carteira de Trabalho;<\/p>\n\n\n\n<p><strong>Requisitos Obrigat\u00f3rios <\/strong>&#8211; ter experi\u00eancia com atendimento ao cliente, conhecimento em Inform\u00e1tica b\u00e1sica e possuir documenta\u00e7\u00e3o completa;<\/p>\n\n\n\n<p><strong>Atividades &#8211; <\/strong>atuar no suporte \u00e0s rotinas administrativas, organiza\u00e7\u00e3o de documentos e lan\u00e7amentos em sistemas, contribuindo com um ambiente inclusivo, colaborativo e focado na qualidade dos processos.<\/p>\n\n\n\n<p><strong>Dispon\u00edvel at\u00e9 10\/7\/2026 ou encerramento da vaga<\/strong><\/p>\n\n\n\n<p>&#8212; &#8212; &#8212;<\/p>\n\n\n\n<p><strong>Texto<\/strong>&nbsp;&#8211;&nbsp;Divulga\u00e7\u00e3o\/Semtepi<\/p>\n\n\n\n<p><strong>Fotos<\/strong>&nbsp;&#8211;&nbsp;Arquivo\/Semcom<\/p>\n\n\n\n<p><strong>Dispon\u00edveis em<\/strong>&nbsp;&#8211;&nbsp;<a href=\"https:\/\/flic.kr\/s\/aHBqjCetWK\">https:\/\/flic.kr\/s\/aHBqjCetWK<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":39,"featured_media":6626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1438,1873,7,9,10],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7<\/title>\n<meta name=\"description\" content=\"A Prefeitura de Manaus, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Manaus, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMTEPI\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-09T18:09:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T18:13:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruna Greco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna Greco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"50 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/\"},\"author\":{\"name\":\"Bruna Greco\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/person\/05d223aea2bf115f9883a6ff3683d81b\"},\"headline\":\"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7\",\"datePublished\":\"2026-07-09T18:09:59+00:00\",\"dateModified\":\"2026-07-09T18:13:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/\"},\"wordCount\":10844,\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg\",\"keywords\":[\"10\/7\",\"779 vagas de emprego\",\"oportunidade\",\"Semtepi\",\"sine manaus\"],\"articleSection\":[\"Oportunidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/\",\"name\":\"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg\",\"datePublished\":\"2026-07-09T18:09:59+00:00\",\"dateModified\":\"2026-07-09T18:13:26+00:00\",\"description\":\"A Prefeitura de Manaus, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg\",\"width\":799,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#website\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/\",\"name\":\"SEMTEPI\",\"description\":\"Prefeitura de Manaus\",\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#organization\"},\"alternateName\":\"Secretaria Municipal do Trabalho, Empreendedorismo e Inova\u00e7\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#organization\",\"name\":\"Prefeitura Municipal de Manaus\",\"alternateName\":\"Prefeitura de Manaus\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2024\/07\/favicon.png\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2024\/07\/favicon.png\",\"width\":300,\"height\":300,\"caption\":\"Prefeitura Municipal de Manaus\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/person\/05d223aea2bf115f9883a6ff3683d81b\",\"name\":\"Bruna Greco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9c877d1a6adc2a055330e5c09a8653ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9c877d1a6adc2a055330e5c09a8653ce?s=96&d=mm&r=g\",\"caption\":\"Bruna Greco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7","description":"A Prefeitura de Manaus, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7","og_description":"A Prefeitura de Manaus, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7.","og_url":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/","og_site_name":"SEMTEPI","article_published_time":"2026-07-09T18:09:59+00:00","article_modified_time":"2026-07-09T18:13:26+00:00","og_image":[{"width":799,"height":533,"url":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg","type":"image\/jpeg"}],"author":"Bruna Greco","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bruna Greco","Est. reading time":"50 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#article","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/"},"author":{"name":"Bruna Greco","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/person\/05d223aea2bf115f9883a6ff3683d81b"},"headline":"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7","datePublished":"2026-07-09T18:09:59+00:00","dateModified":"2026-07-09T18:13:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/"},"wordCount":10844,"publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#organization"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg","keywords":["10\/7","779 vagas de emprego","oportunidade","Semtepi","sine manaus"],"articleSection":["Oportunidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/","url":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/","name":"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg","datePublished":"2026-07-09T18:09:59+00:00","dateModified":"2026-07-09T18:13:26+00:00","description":"A Prefeitura de Manaus, por meio do Sine Manaus, oferta 779 vagas de emprego em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o, nesta sexta-feira, 10\/7.","breadcrumb":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#primaryimage","url":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg","contentUrl":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2025\/07\/54523734531_85fa27d4a0_c-1.jpg","width":799,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/oportunidade\/sine-manaus-779-vagas-emprego-10-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.manaus.am.gov.br\/semtepi\/"},{"@type":"ListItem","position":2,"name":"Sine Manaus oferta 779 vagas de emprego nesta sexta-feira, 10\/7"}]},{"@type":"WebSite","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#website","url":"https:\/\/www.manaus.am.gov.br\/semtepi\/","name":"SEMTEPI","description":"Prefeitura de Manaus","publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#organization"},"alternateName":"Secretaria Municipal do Trabalho, Empreendedorismo e Inova\u00e7\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manaus.am.gov.br\/semtepi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#organization","name":"Prefeitura Municipal de Manaus","alternateName":"Prefeitura de Manaus","url":"https:\/\/www.manaus.am.gov.br\/semtepi\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/logo\/image\/","url":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2024\/07\/favicon.png","contentUrl":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-content\/uploads\/sites\/20\/2024\/07\/favicon.png","width":300,"height":300,"caption":"Prefeitura Municipal de Manaus"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/person\/05d223aea2bf115f9883a6ff3683d81b","name":"Bruna Greco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semtepi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9c877d1a6adc2a055330e5c09a8653ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c877d1a6adc2a055330e5c09a8653ce?s=96&d=mm&r=g","caption":"Bruna Greco"}}]}},"_links":{"self":[{"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/posts\/8359"}],"collection":[{"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/comments?post=8359"}],"version-history":[{"count":1,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/posts\/8359\/revisions"}],"predecessor-version":[{"id":8360,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/posts\/8359\/revisions\/8360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/media\/6626"}],"wp:attachment":[{"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/media?parent=8359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/categories?post=8359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semtepi\/wp-json\/wp\/v2\/tags?post=8359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}