{"id":1241,"date":"2025-06-22T09:21:09","date_gmt":"2025-06-22T13:21:09","guid":{"rendered":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/"},"modified":"2025-07-16T10:12:43","modified_gmt":"2025-07-16T14:12:43","slug":"conferencia-propostas-aprovadas","status":"publish","type":"post","link":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/","title":{"rendered":"4\u00aa Confer\u00eancia Municipal das Cidades encerra com propostas aprovadas e elei\u00e7\u00e3o de delegados para etapa estadual"},"content":{"rendered":"\n<p>A Prefeitura de Manaus, por meio da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf), encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades. O evento foi marcado pela aprova\u00e7\u00e3o das propostas constru\u00eddas coletivamente nos tr\u00eas eixos tem\u00e1ticos e pela escolha dos delegados que representar\u00e3o Manaus na Confer\u00eancia Estadual, prevista para ocorrer at\u00e9 o final de agosto.<\/p>\n\n\n\n<p>Durante dois dias, representantes do poder p\u00fablico, movimentos sociais, entidades civis, conselhos profissionais, acad\u00eamicos e popula\u00e7\u00e3o em geral debateram os principais desafios e solu\u00e7\u00f5es para o desenvolvimento urbano, a pol\u00edtica habitacional e a constru\u00e7\u00e3o de cidades mais justas, inclusivas e sustent\u00e1veis.<\/p>\n\n\n\n<p>Os temas discutidos foram distribu\u00eddos em tr\u00eas eixos: Articula\u00e7\u00e3o entre os principais setores urbanos e o planejamento das pol\u00edticas p\u00fablicas; Gest\u00e3o estrat\u00e9gica e financiamento e Grandes temas transversais, que envolvem quest\u00f5es ambientais, sociais, territoriais e econ\u00f4micas.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios, Jesus Alves, destacou que a confer\u00eancia reafirma o compromisso da gest\u00e3o municipal em ouvir a sociedade para a constru\u00e7\u00e3o de pol\u00edticas p\u00fablicas mais eficazes e democr\u00e1ticas.<\/p>\n\n\n\n<p>\u201cN\u00f3s sa\u00edmos daqui mais fortalecidos. As propostas aprovadas nas salas tem\u00e1ticas s\u00e3o fruto do di\u00e1logo, da escuta e do comprometimento de cada participante. \u00c9 assim que se constroem pol\u00edticas p\u00fablicas: de forma participativa, olhando para as necessidades reais da cidade e da sua gente\u201d, afirmou.<\/p>\n\n\n\n<p>Representando os povos origin\u00e1rios, a coordenadora da Comiss\u00e3o de Terra e Moradia da Coordena\u00e7\u00e3o dos Povos Ind\u00edgenas de Manaus e Entorno (Copemi), Marcelly Munduruku, refor\u00e7ou a import\u00e2ncia da participa\u00e7\u00e3o dos povos ind\u00edgenas na defini\u00e7\u00e3o das pol\u00edticas urbanas.<\/p>\n\n\n\n<p>\u201cA nossa presen\u00e7a aqui n\u00e3o \u00e9 apenas simb\u00f3lica. Somos parte da cidade e precisamos estar inclu\u00eddos nas discuss\u00f5es sobre moradia, regulariza\u00e7\u00e3o fundi\u00e1ria, meio ambiente e desenvolvimento urbano. \u00c9 fundamental que as pol\u00edticas p\u00fablicas considerem nossas especificidades, nossas lutas e nossos direitos enquanto povos origin\u00e1rios que vivem na cidade\u201d, pontuou.<\/p>\n\n\n\n<p>Com o encerramento da etapa municipal, as propostas aprovadas ser\u00e3o sistematizadas e encaminhadas para a etapa estadual, onde seguir\u00e3o contribuindo com a formula\u00e7\u00e3o de diretrizes para a Pol\u00edtica Nacional de Desenvolvimento Urbano.<\/p>\n\n\n\n<p>&#8212; &#8212; &#8212;<\/p>\n\n\n\n<p><strong>Texto &#8211; Leonardo Fierro \/ Semhaf<\/strong><\/p>\n\n\n\n<p><strong>Fotos &#8211; Jo\u00e3o Viana \/ Semcom<\/strong><\/p>\n\n\n\n<p><strong>Dispon\u00edveis em \u2013<\/strong> <a href=\"https:\/\/flic.kr\/s\/aHBqjCiTzD\">https:\/\/flic.kr\/s\/aHBqjCiTzD<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":57,"featured_media":1242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[309,5,6],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confer\u00eancia encerra com propostas aprovadas e elei\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"A Prefeitura de Manaus, por meio da Semhaf, encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confer\u00eancia encerra com propostas aprovadas e elei\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Manaus, por meio da Semhaf, encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMHAF\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-22T13:21:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T14:12:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thiago Fernando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thiago Fernando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/\"},\"author\":{\"name\":\"Thiago Fernando\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882\"},\"headline\":\"4\u00aa Confer\u00eancia Municipal das Cidades encerra com propostas aprovadas e elei\u00e7\u00e3o de delegados para etapa estadual\",\"datePublished\":\"2025-06-22T13:21:09+00:00\",\"dateModified\":\"2025-07-16T14:12:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg\",\"keywords\":[\"Confer\u00eancia Municipal das Cidades\",\"prefeitura de manaus\",\"Semhaf\"],\"articleSection\":[\"Habita\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/\",\"name\":\"Confer\u00eancia encerra com propostas aprovadas e elei\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg\",\"datePublished\":\"2025-06-22T13:21:09+00:00\",\"dateModified\":\"2025-07-16T14:12:43+00:00\",\"description\":\"A Prefeitura de Manaus, por meio da Semhaf, encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg\",\"width\":799,\"height\":533,\"caption\":\"Confer\u00eancia Municipal das Cidades\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4\u00aa Confer\u00eancia Municipal das Cidades encerra com propostas aprovadas e elei\u00e7\u00e3o de delegados para etapa estadual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#website\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/\",\"name\":\"SENHAF\",\"description\":\"SENHAF\",\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization\"},\"alternateName\":\"Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization\",\"name\":\"Prefeitura de Manaus\",\"alternateName\":\"Prefeitura Municipal de Manaus\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Prefeitura de Manaus\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882\",\"name\":\"Thiago Fernando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g\",\"caption\":\"Thiago Fernando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confer\u00eancia encerra com propostas aprovadas e elei\u00e7\u00e3o","description":"A Prefeitura de Manaus, por meio da Semhaf, encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Confer\u00eancia encerra com propostas aprovadas e elei\u00e7\u00e3o","og_description":"A Prefeitura de Manaus, por meio da Semhaf, encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades.","og_url":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/","og_site_name":"SEMHAF","article_published_time":"2025-06-22T13:21:09+00:00","article_modified_time":"2025-07-16T14:12:43+00:00","og_image":[{"width":799,"height":533,"url":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg","type":"image\/jpeg"}],"author":"Thiago Fernando","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Thiago Fernando","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#article","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/"},"author":{"name":"Thiago Fernando","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882"},"headline":"4\u00aa Confer\u00eancia Municipal das Cidades encerra com propostas aprovadas e elei\u00e7\u00e3o de delegados para etapa estadual","datePublished":"2025-06-22T13:21:09+00:00","dateModified":"2025-07-16T14:12:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/"},"wordCount":434,"publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg","keywords":["Confer\u00eancia Municipal das Cidades","prefeitura de manaus","Semhaf"],"articleSection":["Habita\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/","name":"Confer\u00eancia encerra com propostas aprovadas e elei\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg","datePublished":"2025-06-22T13:21:09+00:00","dateModified":"2025-07-16T14:12:43+00:00","description":"A Prefeitura de Manaus, por meio da Semhaf, encerrou na noite deste s\u00e1bado, 21\/6, a 4\u00aa Confer\u00eancia Municipal das Cidades.","breadcrumb":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#primaryimage","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg","contentUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/Conferencia-_Semhaf-3.jpg","width":799,"height":533,"caption":"Confer\u00eancia Municipal das Cidades"},{"@type":"BreadcrumbList","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/conferencia-propostas-aprovadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.manaus.am.gov.br\/semhaf\/"},{"@type":"ListItem","position":2,"name":"4\u00aa Confer\u00eancia Municipal das Cidades encerra com propostas aprovadas e elei\u00e7\u00e3o de delegados para etapa estadual"}]},{"@type":"WebSite","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#website","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/","name":"SENHAF","description":"SENHAF","publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization"},"alternateName":"Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manaus.am.gov.br\/semhaf\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization","name":"Prefeitura de Manaus","alternateName":"Prefeitura Municipal de Manaus","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png","width":512,"height":512,"caption":"Prefeitura de Manaus"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882","name":"Thiago Fernando","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g","caption":"Thiago Fernando"}}]}},"_links":{"self":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts\/1241"}],"collection":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/comments?post=1241"}],"version-history":[{"count":1,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts\/1241\/revisions"}],"predecessor-version":[{"id":1248,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts\/1241\/revisions\/1248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/media\/1242"}],"wp:attachment":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/media?parent=1241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/categories?post=1241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/tags?post=1241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}