{"id":1205,"date":"2025-06-16T13:33:16","date_gmt":"2025-06-16T17:33:16","guid":{"rendered":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/"},"modified":"2025-07-03T13:53:49","modified_gmt":"2025-07-03T17:53:49","slug":"dois-anos-da-semhaf","status":"publish","type":"post","link":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/","title":{"rendered":"Prefeitura de Manaus \u00e9 homenageada na CMM pelos dois anos da Semhaf"},"content":{"rendered":"\n<p>A Prefeitura de Manaus foi homenageada, na manh\u00e3 desta segunda-feira, 16\/6, durante uma Sess\u00e3o Solene na C\u00e2mara Municipal de Manaus (CMM) em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf). A solenidade, proposta pelo vereador Gilmar Nascimento, destacou o trabalho da gest\u00e3o municipal na transforma\u00e7\u00e3o da pol\u00edtica habitacional da cidade, levando dignidade, seguran\u00e7a jur\u00eddica e qualidade de vida para milhares de fam\u00edlias.<\/p>\n\n\n\n<p>Ao longo desses dois anos, a Prefeitura de Manaus consolidou um dos maiores programas de regulariza\u00e7\u00e3o fundi\u00e1ria do pa\u00eds, com mais de 10 mil registros definitivos de im\u00f3veis entregues. Al\u00e9m disso, a Prefeitura executa hoje o maior programa habitacional da sua hist\u00f3ria, com 4.700 unidades habitacionais contratadas, al\u00e9m de ter implantado o programa Casa Manauara, que j\u00e1 reformou mais de 400 casas de fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade social.<\/p>\n\n\n\n<p>O subsecret\u00e1rio da Semhaf, Zuldy Bonates, representando o secret\u00e1rio Jesus Alves, destacou o avan\u00e7o da pol\u00edtica habitacional em Manaus como resultado da uni\u00e3o de esfor\u00e7os.<\/p>\n\n\n\n<p>\u201cEsse trabalho s\u00f3 \u00e9 poss\u00edvel gra\u00e7as ao apoio do nosso prefeito David Almeida, que abra\u00e7ou essa causa e n\u00e3o mede esfor\u00e7os para garantir moradia digna para quem mais precisa. Tamb\u00e9m n\u00e3o posso deixar de agradecer ao senador Eduardo Braga, que tem sido incans\u00e1vel na destina\u00e7\u00e3o de recursos para que possamos transformar a vida das pessoas. Quando chegamos \u00e0 secretaria, entreg\u00e1vamos cerca de 500 t\u00edtulos por ano. Hoje, dois anos depois, Manaus ultrapassa a marca de 10 mil t\u00edtulos entregues, al\u00e9m de termos mais de 4.700 unidades habitacionais contratadas. Isso \u00e9 fruto de uma gest\u00e3o que entende que habita\u00e7\u00e3o \u00e9 dignidade, \u00e9 justi\u00e7a social e transforma\u00e7\u00e3o\u201d, afirmou Zuldy.<\/p>\n\n\n\n<p>Ele tamb\u00e9m lembrou que a Prefeitura de Manaus est\u00e1 inovando ao criar projetos como o \u201cManaus Minha Terra\u201d, que promove a ocupa\u00e7\u00e3o planejada de \u00e1reas, como o novo bairro planejado Dorothea Braga, que ter\u00e1 3.600 lotes urbanizados, com infraestrutura completa: \u00e1gua, energia, asfalto, escola, UBS, creche e at\u00e9 base da Guarda Ambiental Municipal.<\/p>\n\n\n\n<p>O vereador Gilmar Nascimento, autor da homenagem, ressaltou a import\u00e2ncia da Prefeitura assumir o protagonismo na pol\u00edtica habitacional de Manaus.<\/p>\n\n\n\n<p>\u201cPor muito tempo, a pol\u00edtica de habita\u00e7\u00e3o esteve centralizada no Estado e na Uni\u00e3o. Com a cria\u00e7\u00e3o da Semhaf, a Prefeitura de Manaus passou a ter um canal direto para acessar recursos e executar programas pr\u00f3prios, como o Casa Manauara, a regulariza\u00e7\u00e3o fundi\u00e1ria e os projetos habitacionais. A Constitui\u00e7\u00e3o fala de direito \u00e0 moradia, que vai muito al\u00e9m de uma constru\u00e7\u00e3o f\u00edsica. Moradia \u00e9 dignidade, \u00e9 qualidade de vida, \u00e9 ter um lar de verdade\u201d, concluiu o parlamentar.<\/p>\n\n\n\n<p>&#8212; &#8212; &#8212;<\/p>\n\n\n\n<p><strong>Texto &#8211; <\/strong>Leonardo Fierro \/ Semhaf<strong><\/strong><\/p>\n\n\n\n<p><strong>Fotos &#8211; <\/strong>Levy Moraes \/ Semhaf<strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":57,"featured_media":1206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[307,13,5,6],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PMM \u00e9 homenageada na CMM pelos dois anos da Semhaf<\/title>\n<meta name=\"description\" content=\"A PMM foi homenageada em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf).\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PMM \u00e9 homenageada na CMM pelos dois anos da Semhaf\" \/>\n<meta property=\"og:description\" content=\"A PMM foi homenageada em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMHAF\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-16T17:33:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T17:53:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"4113\" \/>\n\t<meta property=\"og:image:height\" content=\"2742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thiago Fernando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thiago Fernando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/\"},\"author\":{\"name\":\"Thiago Fernando\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882\"},\"headline\":\"Prefeitura de Manaus \u00e9 homenageada na CMM pelos dois anos da Semhaf\",\"datePublished\":\"2025-06-16T17:33:16+00:00\",\"dateModified\":\"2025-07-03T17:53:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/\"},\"wordCount\":486,\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg\",\"keywords\":[\"dois anos da Semhaf\",\"habita\u00e7\u00e3o\",\"prefeitura de manaus\",\"Semhaf\"],\"articleSection\":[\"Habita\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/\",\"name\":\"PMM \u00e9 homenageada na CMM pelos dois anos da Semhaf\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg\",\"datePublished\":\"2025-06-16T17:33:16+00:00\",\"dateModified\":\"2025-07-03T17:53:49+00:00\",\"description\":\"A PMM foi homenageada em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg\",\"width\":4113,\"height\":2742,\"caption\":\"dois anos da Semhaf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura de Manaus \u00e9 homenageada na CMM pelos dois anos da Semhaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#website\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/\",\"name\":\"SENHAF\",\"description\":\"SENHAF\",\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization\"},\"alternateName\":\"Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization\",\"name\":\"Prefeitura de Manaus\",\"alternateName\":\"Prefeitura Municipal de Manaus\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Prefeitura de Manaus\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882\",\"name\":\"Thiago Fernando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g\",\"caption\":\"Thiago Fernando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PMM \u00e9 homenageada na CMM pelos dois anos da Semhaf","description":"A PMM foi homenageada em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf).","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"PMM \u00e9 homenageada na CMM pelos dois anos da Semhaf","og_description":"A PMM foi homenageada em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf).","og_url":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/","og_site_name":"SEMHAF","article_published_time":"2025-06-16T17:33:16+00:00","article_modified_time":"2025-07-03T17:53:49+00:00","og_image":[{"width":4113,"height":2742,"url":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg","type":"image\/jpeg"}],"author":"Thiago Fernando","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Thiago Fernando","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#article","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/"},"author":{"name":"Thiago Fernando","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882"},"headline":"Prefeitura de Manaus \u00e9 homenageada na CMM pelos dois anos da Semhaf","datePublished":"2025-06-16T17:33:16+00:00","dateModified":"2025-07-03T17:53:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/"},"wordCount":486,"publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg","keywords":["dois anos da Semhaf","habita\u00e7\u00e3o","prefeitura de manaus","Semhaf"],"articleSection":["Habita\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/","name":"PMM \u00e9 homenageada na CMM pelos dois anos da Semhaf","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg","datePublished":"2025-06-16T17:33:16+00:00","dateModified":"2025-07-03T17:53:49+00:00","description":"A PMM foi homenageada em reconhecimento aos dois anos de cria\u00e7\u00e3o da Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (Semhaf).","breadcrumb":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#primaryimage","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg","contentUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2025\/06\/dois-anos-da-Semhaf-2.jpeg","width":4113,"height":2742,"caption":"dois anos da Semhaf"},{"@type":"BreadcrumbList","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/dois-anos-da-semhaf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.manaus.am.gov.br\/semhaf\/"},{"@type":"ListItem","position":2,"name":"Prefeitura de Manaus \u00e9 homenageada na CMM pelos dois anos da Semhaf"}]},{"@type":"WebSite","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#website","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/","name":"SENHAF","description":"SENHAF","publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization"},"alternateName":"Secretaria Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manaus.am.gov.br\/semhaf\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#organization","name":"Prefeitura de Manaus","alternateName":"Prefeitura Municipal de Manaus","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/","url":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-content\/uploads\/sites\/28\/2023\/11\/cropped-favicon.png","width":512,"height":512,"caption":"Prefeitura de Manaus"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/a5ee5376db6e21af026374b369f30882","name":"Thiago Fernando","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semhaf\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5aab8722444041451501c077052ac07?s=96&d=mm&r=g","caption":"Thiago Fernando"}}]}},"_links":{"self":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts\/1205"}],"collection":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":1,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"predecessor-version":[{"id":1234,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/posts\/1205\/revisions\/1234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/media\/1206"}],"wp:attachment":[{"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semhaf\/wp-json\/wp\/v2\/tags?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}