{"id":212798,"date":"2026-07-09T17:52:15","date_gmt":"2026-07-09T21:52:15","guid":{"rendered":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/"},"modified":"2026-07-10T12:52:52","modified_gmt":"2026-07-10T16:52:52","slug":"programa-manaus-que-a-gente-cuida-4","status":"publish","type":"post","link":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/","title":{"rendered":"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina"},"content":{"rendered":"\n<p>A <a href=\"https:\/\/www.manaus.am.gov.br\/\">Prefeitura de Manaus<\/a> deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d, mobilizando uma grande estrutura no bairro Santa Etelvina, zona Norte. O mutir\u00e3o integrado, que une servi\u00e7os essenciais de infraestrutura, limpeza urbana, sa\u00fade, assist\u00eancia social, tr\u00e2nsito e ordenamento, visa promover uma transforma\u00e7\u00e3o imediata na qualidade de vida e na mobilidade da comunidade.<\/p>\n\n\n\n<p>O ponto central de atendimento \u00e0 popula\u00e7\u00e3o est\u00e1 concentrado na escola municipal Presidente Jo\u00e3o Goulart, na rua Samambaia, n\u00ba 39, com a oferta de a\u00e7\u00f5es sociais, de sa\u00fade e habitacionais, que ocorrem nesta quinta e sexta-feira, das 8h \u00e0s 14h, e no s\u00e1bado, das 8h \u00e0s 12h, facilitando o acesso dos moradores a consultas m\u00e9dicas, vacina\u00e7\u00e3o e atualiza\u00e7\u00e3o do Cadastro \u00danico (Cad\u00danico). Conforme o planejamento do comit\u00ea integrado municipal, as pr\u00f3ximas edi\u00e7\u00f5es do programa j\u00e1 est\u00e3o sendo alinhadas para contemplar bairros como Cidade Nova, Compensa e Reden\u00e7\u00e3o.<\/p>\n\n\n\n<p>As equipes de obras e limpeza p\u00fablica iniciaram os trabalhos mapeando as car\u00eancias do bairro, com foco em opera\u00e7\u00f5es tapa-buracos, recupera\u00e7\u00e3o de vias, desobstru\u00e7\u00e3o de bueiros, varri\u00e7\u00e3o, capina\u00e7\u00e3o e moderniza\u00e7\u00e3o do sistema de ilumina\u00e7\u00e3o. O titular da <a href=\"https:\/\/www.instagram.com\/seminf.manaus\/\">Secretaria Municipal de Infraestrutura<\/a> (Seminf), Madson Rodrigues, destacou a agilidade e a dedica\u00e7\u00e3o das equipes envolvidas no mutir\u00e3o.<\/p>\n\n\n\n<p>&#8220;Viemos aqui para atender e contemplar as demandas da comunidade com manuten\u00e7\u00e3o intensiva. Nossas equipes mapearam, j\u00e1 na noite anterior, os pontos onde h\u00e1 necessidade de manuten\u00e7\u00e3o de lumin\u00e1rias ou trocas, al\u00e9m da desobstru\u00e7\u00e3o de bueiros. A determina\u00e7\u00e3o do prefeito \u00e9 vir e resolver, garantindo a dignidade que a popula\u00e7\u00e3o precisa&#8221;, informou.<\/p>\n\n\n\n<p>Para os moradores, a chegada das frentes de obras representa o fim de um per\u00edodo de espera. O conselheiro municipal de sa\u00fade, Arlison Rodrigues, expressou a satisfa\u00e7\u00e3o da comunidade com as melhorias nas ruas. &#8220;Isso \u00e9 muito bom, \u00e9 uma alegria ter esse servi\u00e7o para a nossa comunidade. Isso \u00e9 muito importante para toda Manaus e o bairro Santa Etelvina est\u00e1 muito agradecido&#8221;, disse.<\/p>\n\n\n\n<p>A l\u00edder comunit\u00e1ria Sueli Oliveira tamb\u00e9m refor\u00e7ou o impacto positivo das a\u00e7\u00f5es de manuten\u00e7\u00e3o urbana diretamente no dia a dia dos moradores. &#8220;Para a gente da comunidade do Santa Etelvina \u00e9 muito importante. As a\u00e7\u00f5es que est\u00e3o sendo feitas de tapa-buracos e limpeza das ruas s\u00f3 trazem benef\u00edcios. A gente s\u00f3 quer agradecer \u00e0 Prefeitura de Manaus por essa a\u00e7\u00e3o e que v\u00e1rias outras aconte\u00e7am na nossa comunidade\u201d, agradeceu.<\/p>\n\n\n\n<p><strong>Assist\u00eancia Social e Lazer<\/strong><\/p>\n\n\n\n<p>A Secretaria Municipal de Mulher, Assist\u00eancia Social e Cidadania (Semasc) est\u00e1 com mais de 30 ve\u00edculos nas ruas para realizar atendimento psicossocial e o acompanhamento das fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade no bairro. Al\u00e9m disso, para estender o impacto do mutir\u00e3o, o bairro vai receber no s\u00e1bado, 11\/7, a\u00e7\u00f5es especiais de esporte e lazer coordenadas pela Secretaria Municipal de Juventude, Esporte e Lazer (Semjel).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1024x682.jpeg\" alt=\"\" class=\"wp-image-212799\" srcset=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1024x682.jpeg 1024w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-300x200.jpeg 300w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-768x512.jpeg 768w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1536x1023.jpeg 1536w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">#paratodosverem &#8211; Agente da Semasc realizando orienta\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O secret\u00e1rio da Semasc, Wanderson Costa, fez um alerta importante sobre o funcionamento do sistema nacional do Cadastro \u00danico nos pr\u00f3ximos dias, garantindo que nenhum morador ser\u00e1 prejudicado pelas manuten\u00e7\u00f5es do governo federal.<\/p>\n\n\n\n<p>&#8220;Nos dias 10 e 11 (sexta-feira e s\u00e1bado), o sistema federal para o Cad\u00danico estar\u00e1 inoperante. Mas quero tranquilizar a popula\u00e7\u00e3o do Santa Etelvina, nossa equipe da assist\u00eancia social estar\u00e1 nas ruas fazendo visitas individuais porta a porta. J\u00e1 temos um pr\u00e9-cadastro das pessoas agendadas para desbloqueio de benef\u00edcios ou novos cadastros, e daremos esse atendimento direto nas resid\u00eancias&#8221;, garantiu.<\/p>\n\n\n\n<p>A Semasc tamb\u00e9m atua com o cadastramento de fam\u00edlias unipessoais e relembrou as a\u00e7\u00f5es recentes na comunidade, como a entrega de pescado por meio do programa &#8220;Jaraqui da Gente&#8221;, que beneficiou mais de dois mil moradores do bairro. O mutir\u00e3o conta ainda com uma a\u00e7\u00e3o de ordenamento do com\u00e9rcio informal coordenado pela Secretaria Municipal de Agricultura, Abastecimento, Centro e Com\u00e9rcio Informal (Semacc) nas principais vias.<\/p>\n\n\n\n<p><strong>Interven\u00e7\u00f5es no tr\u00e2nsito<\/strong><\/p>\n\n\n\n<p>Para melhorar a fluidez e reduzir os riscos de acidentes nas vias mapeadas, o Instituto Municipal de Mobilidade Urbana (IMMU) implementou interven\u00e7\u00f5es profundas na sinaliza\u00e7\u00e3o e na geometria do tr\u00e2nsito local. O diretor-presidente do IMMU, Elson Andrade, detalhou as mudan\u00e7as estruturais na regi\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.36-1024x682.jpeg\" alt=\"\" class=\"wp-image-212801\" srcset=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.36-1024x682.jpeg 1024w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.36-300x200.jpeg 300w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.36-768x512.jpeg 768w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.36-1536x1023.jpeg 1536w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.36.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">#paratodosverem &#8211; Agentes do IMMU realizando monitoramento<\/figcaption><\/figure>\n\n\n\n<p>&#8220;Nesta madrugada, o IMMU implantou sinaliza\u00e7\u00f5es verticais e horizontais, revitalizou faixas de pedestres e lombadas para refor\u00e7ar a seguran\u00e7a. Uma das principais medidas \u00e9 a mudan\u00e7a no sentido de circula\u00e7\u00e3o das ruas Samambaia e Balbina Mestrinho, que passam a operar em m\u00e3o \u00fanica, visando aumentar a seguran\u00e7a vi\u00e1ria. Tamb\u00e9m estamos estudando a implanta\u00e7\u00e3o de um sem\u00e1foro com botoeira na avenida 7 de Setembro para garantir a travessia segura dos pedestres contra motoristas imprudentes&#8221;, esclareceu.<\/p>\n\n\n\n<p>A descentraliza\u00e7\u00e3o dos servi\u00e7os municipais foi apontada pelos moradores como um dos pontos altos do mutir\u00e3o, poupando tempo e custos de deslocamento. A moradora Lilian Freitas Monteiro, que aproveitou a estrutura na escola para atualizar seus documentos, destacou a conveni\u00eancia da a\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;\u00c9 muito importante devido \u00e0 alta demanda por esses servi\u00e7os, como a atualiza\u00e7\u00e3o do Cadastro \u00danico. \u00c0s vezes, a gente n\u00e3o consegue pelo site e \u00e9 importante, porque adianta. Minha filha estuda aqui na escola, eu fiquei sabendo pelo grupo e j\u00e1 vim fazer minha atualiza\u00e7\u00e3o. Vou aproveitar tamb\u00e9m para tirar minha certid\u00e3o. Ent\u00e3o, para mim est\u00e1 valendo muito a pena&#8221;, comentou.<\/p>\n\n\n\n<p>A facilidade de acesso tamb\u00e9m foi elogiada pela professora Stella Karoline, que enfatizou como a uni\u00e3o de v\u00e1rias pastas em um s\u00f3 lugar ajuda quem mora longe do centro urbano. &#8220;A quest\u00e3o da a\u00e7\u00e3o \u00e9 muito importante para a comunidade, porque alguns servi\u00e7os se tornam ali mais f\u00e1ceis, o acesso fica mais perto. Muitos n\u00e3o conseguem se locomover a locais distantes e essa a\u00e7\u00e3o aproxima os servi\u00e7os. A popula\u00e7\u00e3o tem que aproveitar. Convido todos a participarem&#8221;, pontuou.<\/p>\n\n\n\n<p><strong>Sa\u00fade e preven\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Na \u00e1rea da sa\u00fade, as a\u00e7\u00f5es foram descentralizadas para cobrir o maior n\u00famero poss\u00edvel de moradores do Santa Etelvina. O titular da Secretaria Municipal de Sa\u00fade (Semsa), Nagib Salem, destacou o refor\u00e7o no atendimento m\u00e9dico e preventivo montado na comunidade.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-212800\" srcset=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1-1024x682.jpeg 1024w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1-300x200.jpeg 300w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1-768x512.jpeg 768w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1-1536x1023.jpeg 1536w, https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.38-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">#paratodosverem &#8211; M\u00e9dica da Semsa realizando exame <\/figcaption><\/figure>\n\n\n\n<p>&#8220;Estamos aqui com a Unidade B\u00e1sica de Sa\u00fade (UBS) S\u00e1lvio Belota e com equipes na escola municipal Jo\u00e3o Goulart refor\u00e7ando a vacina\u00e7\u00e3o, testes r\u00e1pidos e consultas m\u00e9dicas. Trouxemos profissionais de toda a rede para somar for\u00e7as. Vale lembrar que a S\u00e1lvio Belota \u00e9 uma unidade que j\u00e1 funciona em hor\u00e1rio estendido, inclusive aos s\u00e1bados, das 8h ao meio-dia. A determina\u00e7\u00e3o do prefeito \u00e9 irmos ao encontro da popula\u00e7\u00e3o, e estamos felizes em trazer a sa\u00fade para perto de quem mais precisa&#8221;, disse Nagib.<\/p>\n\n\n\n<p><strong>Compromisso<\/strong><\/p>\n\n\n\n<p>Ao levar os \u00f3rg\u00e3os p\u00fablicos municipais diretamente para dentro dos bairros, o programa &#8220;Manaus que a Gente Cuida&#8221; reafirma a diretriz da prefeitura de encurtar dist\u00e2ncias entre a administra\u00e7\u00e3o p\u00fablica e o cidad\u00e3o.<\/p>\n\n\n\n<p>A iniciativa quebra barreiras burocr\u00e1ticas ao transformar espa\u00e7os comunit\u00e1rios em polos de cidadania, garantindo que os servi\u00e7os essenciais cheguem com agilidade a quem mais precisa. Mais do que um pacote de obras e atendimentos, a presen\u00e7a integrada das secretarias no Santa Etelvina consolida um modelo de gest\u00e3o humanizada, focado em ouvir as demandas locais e devolver dignidade, bem-estar e infraestrutura diretamente na porta dos manauaras.<\/p>\n\n\n\n<p>&#8212; &#8212; &#8212;<br><strong>Texto \u2013<\/strong> Geraldo Farias\/Semcom<br><strong>Fotos \u2013<\/strong> Ant\u00f4nio Pereira e Jo\u00e3o Viana\/Semcom<br><strong>Dispon\u00edveis em <\/strong>\u2013 <a href=\"https:\/\/flic.kr\/s\/aHBqjCYK3k\">https:\/\/flic.kr\/s\/aHBqjCYK3k<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":212802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[539],"tags":[1622,432,7,1478,1623],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina<\/title>\n<meta name=\"description\" content=\"A Prefeitura de Manaus deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Manaus deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMASC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/semascmanaus\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-09T21:52:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T16:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bvalente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bvalente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/\"},\"author\":{\"name\":\"bvalente\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/person\/466a0e03ae4b6062809046bd560ac955\"},\"headline\":\"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina\",\"datePublished\":\"2026-07-09T21:52:15+00:00\",\"dateModified\":\"2026-07-10T16:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/\"},\"wordCount\":1338,\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg\",\"keywords\":[\"a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d\",\"atendimentos\",\"prefeitura de manaus\",\"programa\",\"programa \u2018Manaus que a Gente Cuida\u2019\"],\"articleSection\":[\"Atendimento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/\",\"name\":\"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina\",\"isPartOf\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg\",\"datePublished\":\"2026-07-09T21:52:15+00:00\",\"dateModified\":\"2026-07-10T16:52:52+00:00\",\"description\":\"A Prefeitura de Manaus deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg\",\"width\":799,\"height\":533,\"caption\":\"#paratodosverem - Secret\u00e1rio da Semasc, Wanderson Costa e secret\u00e1rios municipais durante entrevista coletiva\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.manaus.am.gov.br\/semasc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#website\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semasc\/\",\"name\":\"SEMASC\",\"description\":\"Secretaria Municipal da Mulher, Assist\u00eancia Social e Cidadania.\",\"publisher\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#organization\"},\"alternateName\":\"Secretaria Municipal da Mulher, Assist\u00eancia Social e Cidadania\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.manaus.am.gov.br\/semasc\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#organization\",\"name\":\"Prefeitura de Manaus\",\"alternateName\":\"Prefeitura Municipal de Manaus\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semasc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2024\/07\/favicon.png\",\"contentUrl\":\"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2024\/07\/favicon.png\",\"width\":300,\"height\":300,\"caption\":\"Prefeitura de Manaus\"},\"image\":{\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/semascmanaus\",\"https:\/\/www.instagram.com\/semascmanaus\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/person\/466a0e03ae4b6062809046bd560ac955\",\"name\":\"bvalente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3e69bc2b014bdad41adfec3a39de07d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3e69bc2b014bdad41adfec3a39de07d2?s=96&d=mm&r=g\",\"caption\":\"bvalente\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina","description":"A Prefeitura de Manaus deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina","og_description":"A Prefeitura de Manaus deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d.","og_url":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/","og_site_name":"SEMASC","article_publisher":"https:\/\/www.facebook.com\/semascmanaus","article_published_time":"2026-07-09T21:52:15+00:00","article_modified_time":"2026-07-10T16:52:52+00:00","og_image":[{"width":799,"height":533,"url":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg","type":"image\/jpeg"}],"author":"bvalente","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bvalente","Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#article","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/"},"author":{"name":"bvalente","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/person\/466a0e03ae4b6062809046bd560ac955"},"headline":"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina","datePublished":"2026-07-09T21:52:15+00:00","dateModified":"2026-07-10T16:52:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/"},"wordCount":1338,"publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#organization"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg","keywords":["a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d","atendimentos","prefeitura de manaus","programa","programa \u2018Manaus que a Gente Cuida\u2019"],"articleSection":["Atendimento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/","url":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/","name":"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina","isPartOf":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg","datePublished":"2026-07-09T21:52:15+00:00","dateModified":"2026-07-10T16:52:52+00:00","description":"A Prefeitura de Manaus deu continuidade, nesta quinta-feira, 9\/7, \u00e0s a\u00e7\u00f5es do programa \u201cManaus que a Gente Cuida\u201d.","breadcrumb":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#primaryimage","url":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg","contentUrl":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2026\/07\/WhatsApp-Image-2026-07-09-at-17.48.50.jpeg","width":799,"height":533,"caption":"#paratodosverem - Secret\u00e1rio da Semasc, Wanderson Costa e secret\u00e1rios municipais durante entrevista coletiva"},{"@type":"BreadcrumbList","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/programa-manaus-que-a-gente-cuida-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.manaus.am.gov.br\/semasc\/"},{"@type":"ListItem","position":2,"name":"Prefeitura intensifica a\u00e7\u00f5es integradas do programa \u2018Manaus que a Gente Cuida\u2019 no bairro Santa Etelvina"}]},{"@type":"WebSite","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#website","url":"https:\/\/www.manaus.am.gov.br\/semasc\/","name":"SEMASC","description":"Secretaria Municipal da Mulher, Assist\u00eancia Social e Cidadania.","publisher":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#organization"},"alternateName":"Secretaria Municipal da Mulher, Assist\u00eancia Social e Cidadania","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manaus.am.gov.br\/semasc\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#organization","name":"Prefeitura de Manaus","alternateName":"Prefeitura Municipal de Manaus","url":"https:\/\/www.manaus.am.gov.br\/semasc\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/logo\/image\/","url":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2024\/07\/favicon.png","contentUrl":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-content\/uploads\/sites\/17\/2024\/07\/favicon.png","width":300,"height":300,"caption":"Prefeitura de Manaus"},"image":{"@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/semascmanaus","https:\/\/www.instagram.com\/semascmanaus\/"]},{"@type":"Person","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/person\/466a0e03ae4b6062809046bd560ac955","name":"bvalente","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.manaus.am.gov.br\/semasc\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3e69bc2b014bdad41adfec3a39de07d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e69bc2b014bdad41adfec3a39de07d2?s=96&d=mm&r=g","caption":"bvalente"}}]}},"_links":{"self":[{"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/posts\/212798"}],"collection":[{"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/comments?post=212798"}],"version-history":[{"count":3,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/posts\/212798\/revisions"}],"predecessor-version":[{"id":212805,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/posts\/212798\/revisions\/212805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/media\/212802"}],"wp:attachment":[{"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/media?parent=212798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/categories?post=212798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manaus.am.gov.br\/semasc\/wp-json\/wp\/v2\/tags?post=212798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}